{"id":2725,"date":"2025-03-12T15:18:43","date_gmt":"2025-03-12T15:18:43","guid":{"rendered":"https:\/\/reporterdafrique.info\/?p=2725"},"modified":"2025-03-01T15:24:02","modified_gmt":"2025-03-01T15:24:02","slug":"togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants","status":"publish","type":"post","link":"https:\/\/reporterdafrique.info\/en\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/","title":{"rendered":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants"},"content":{"rendered":"<p><strong><em>L&rsquo;attribution croissante des bourses nationales aux jeunes togolais est un gros investissement dans l&rsquo;avenir. Tous les ans, le gouvernement togolais se plie en quatre pour garantir un acc\u00e8s \u00e9quitable \u00e0 l&rsquo;\u00e9ducation, notamment en augmentant le nombre de bourses octroy\u00e9es aux apprenants. Ces bourses, destin\u00e9es aux \u00e9l\u00e8ves et aux \u00e9tudiants les plus m\u00e9ritants et\/ou issus de milieux modestes, traduisent un engagement clair envers le d\u00e9veloppement du capital humain.<\/em><\/strong><\/p>\n\n\n\n<p>Le nombre de b\u00e9n\u00e9ficiaires des bourses nationales a connu une hausse notable ces derni\u00e8res ann\u00e9es. Cette augmentation s&rsquo;inscrit dans une volont\u00e9 d&rsquo;encourager l&rsquo;excellence acad\u00e9mique tout en r\u00e9duisant les in\u00e9galit\u00e9s sociales.<\/p>\n\n\n\n<p>Les bourses couvrent divers aspects de la vie \u00e9tudiante, notamment les frais de scolarit\u00e9, le logement, et parfois m\u00eame une allocation pour les d\u00e9penses quotidiennes. Une telle initiative permet aux \u00e9tudiants de se concentrer pleinement sur leurs \u00e9tudes sans les pressions financi\u00e8res qui pourraient compromettre leur r\u00e9ussite.<\/p>\n\n\n\n<p><strong>Un moteur d&rsquo;\u00e9quit\u00e9 et d&rsquo;inclusion sociale<\/strong><\/p>\n\n\n\n<p>L&rsquo;\u00e9largissement du programme de bourses nationales vise \u00e0 inclure des groupes souvent marginalis\u00e9s. Les \u00e9tudiants des zones rurales et les jeunes filles, particuli\u00e8rement vuln\u00e9rables au d\u00e9crochage scolaire, sont des cibles prioritaires. Cette strat\u00e9gie renforce l&rsquo;\u00e9quit\u00e9 en rendant l&rsquo;\u00e9ducation accessible \u00e0 un plus grand nombre de Togolais, ind\u00e9pendamment de leur origine g\u00e9ographique ou de leur genre.<\/p>\n\n\n\n<p>Ce soutien aux apprenants ne se limite pas \u00e0 un simple geste symbolique. Les r\u00e9cipiendaires des bourses sont souvent encourag\u00e9s \u00e0 poursuivre des \u00e9tudes dans des domaines cl\u00e9s pour le d\u00e9veloppement du pays, comme les sciences, la m\u00e9decine, les technologies de l&rsquo;information. Cela contribue \u00e0 l&rsquo;\u00e9mergence d&rsquo;une nouvelle g\u00e9n\u00e9ration de cadres comp\u00e9tents, capables de relever les d\u00e9fis \u00e9conomiques et sociaux du Togo.<\/p>\n\n\n\n<p><strong>15 milliards de francs CFA chaque ann\u00e9e<\/strong><\/p>\n\n\n\n<p>Au rang des grandes r\u00e9formes entreprises pour moderniser et dynamiser le secteur se trouvent les innovations p\u00e9dagogiques visant \u00e0 renforcer la qualit\u00e9 de l&rsquo;enseignement, les politiques ambitieuses de r\u00e9habilitation et de construction d&rsquo;infrastructures universitaires\u2026<\/p>\n\n\n\n<p>Peuvent \u00eatre cit\u00e9s la construction d&rsquo;une troisi\u00e8me universit\u00e9 publique \u00e0 Datcha qui a \u00e9t\u00e9 lanc\u00e9e, le Centre universitaire de p\u00e9dagogie qui est d\u00e9sormais op\u00e9rationnel \u00e0 Lom\u00e9 et les autres chantiers qui permettent d&rsquo;aligner les formations sur les besoins du march\u00e9 du travail.<\/p>\n\n\n\n<p>Le minist\u00e8re de l&rsquo;Enseignement sup\u00e9rieur et de la recherche souligne que des fili\u00e8res prioritaires sont identifi\u00e9es dans les domaines de la sant\u00e9, de l&rsquo;agriculture et de l&rsquo;ing\u00e9nierie, avec pour objectif de r\u00e9pondre aux besoins strat\u00e9giques du pays et que, pour le financement des \u00e9tudes sur fond d&rsquo;\u00e9quit\u00e9 sociale, 15 milliards de francs sont consacr\u00e9s chaque ann\u00e9e aux bourses nationales en compl\u00e9ment des bourses partenariales.<\/p>\n\n\n\n<p>Selon l&rsquo;ex\u00e9cutif, les aides sont attribu\u00e9es en toute transparence, sur l&rsquo;unique base du m\u00e9rite. Le soutien aux jeunes \u00e9tudiants refl\u00e8te une vision, celle tourn\u00e9e vers l&rsquo;avenir, o\u00f9 chaque Togolais a les moyens d&rsquo;atteindre son plein potentiel et de faire avancer le pays.<\/p>\n\n\n\n<p><strong><em>La R\u00e9daction<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;attribution croissante des bourses nationales aux jeunes togolais est un gros investissement dans l&rsquo;avenir. Tous les ans, le gouvernement togolais se plie en quatre pour garantir un acc\u00e8s \u00e9quitable \u00e0 l&rsquo;\u00e9ducation, notamment en augmentant le nombre de bourses octroy\u00e9es aux apprenants. Ces bourses, destin\u00e9es aux \u00e9l\u00e8ves et aux \u00e9tudiants les plus m\u00e9ritants et\/ou issus de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[50],"tags":[],"class_list":{"0":"post-2725","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-societe"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE<\/title>\n<meta name=\"description\" content=\"bourse, apprenant, formation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reporterdafrique.info\/en\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE\" \/>\n<meta property=\"og:description\" content=\"bourse, apprenant, formation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reporterdafrique.info\/en\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/\" \/>\n<meta property=\"og:site_name\" content=\"REPORTERDAFRIQUE\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T15:18:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"reporterdafrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"reporterdafrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/\"},\"author\":{\"name\":\"reporterdafrique\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/#\\\/schema\\\/person\\\/e6c969aa000793e687c5399b5ffbdc77\"},\"headline\":\"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants\",\"datePublished\":\"2025-03-12T15:18:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reporterdafrique.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/qqqqqqqqqq.jpg\",\"articleSection\":[\"soci\u00e9t\u00e9\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/\",\"url\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/\",\"name\":\"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reporterdafrique.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/qqqqqqqqqq.jpg\",\"datePublished\":\"2025-03-12T15:18:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/#\\\/schema\\\/person\\\/e6c969aa000793e687c5399b5ffbdc77\"},\"description\":\"bourse, apprenant, formation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reporterdafrique.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/qqqqqqqqqq.jpg\",\"contentUrl\":\"https:\\\/\\\/reporterdafrique.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/qqqqqqqqqq.jpg\",\"width\":1080,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/reporterdafrique.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/#website\",\"url\":\"https:\\\/\\\/reporterdafrique.info\\\/\",\"name\":\"REPORTERDAFRIQUE\",\"description\":\"L&#039;Afrique au quotidien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reporterdafrique.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reporterdafrique.info\\\/#\\\/schema\\\/person\\\/e6c969aa000793e687c5399b5ffbdc77\",\"name\":\"reporterdafrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g\",\"caption\":\"reporterdafrique\"},\"sameAs\":[\"https:\\\/\\\/reporterdafrique.info\"],\"url\":\"https:\\\/\\\/reporterdafrique.info\\\/en\\\/author\\\/reporterdafrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE","description":"bourse, apprenant, formation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reporterdafrique.info\/en\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/","og_locale":"en_US","og_type":"article","og_title":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE","og_description":"bourse, apprenant, formation","og_url":"https:\/\/reporterdafrique.info\/en\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/","og_site_name":"REPORTERDAFRIQUE","article_published_time":"2025-03-12T15:18:43+00:00","og_image":[{"width":1080,"height":756,"url":"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg","type":"image\/jpeg"}],"author":"reporterdafrique","twitter_card":"summary_large_image","twitter_misc":{"Written by":"reporterdafrique","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#article","isPartOf":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/"},"author":{"name":"reporterdafrique","@id":"https:\/\/reporterdafrique.info\/#\/schema\/person\/e6c969aa000793e687c5399b5ffbdc77"},"headline":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants","datePublished":"2025-03-12T15:18:43+00:00","mainEntityOfPage":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#primaryimage"},"thumbnailUrl":"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg","articleSection":["soci\u00e9t\u00e9"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/","url":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/","name":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants - REPORTERDAFRIQUE","isPartOf":{"@id":"https:\/\/reporterdafrique.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#primaryimage"},"image":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#primaryimage"},"thumbnailUrl":"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg","datePublished":"2025-03-12T15:18:43+00:00","author":{"@id":"https:\/\/reporterdafrique.info\/#\/schema\/person\/e6c969aa000793e687c5399b5ffbdc77"},"description":"bourse, apprenant, formation","breadcrumb":{"@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#primaryimage","url":"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg","contentUrl":"https:\/\/reporterdafrique.info\/wp-content\/uploads\/2025\/03\/qqqqqqqqqq.jpg","width":1080,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/reporterdafrique.info\/togo-des-bourses-nationales-offertes-chaque-annee-aux-apprenants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reporterdafrique.info\/"},{"@type":"ListItem","position":2,"name":"Togo\u00a0: Des bourses nationales offertes chaque ann\u00e9e aux apprenants"}]},{"@type":"WebSite","@id":"https:\/\/reporterdafrique.info\/#website","url":"https:\/\/reporterdafrique.info\/","name":"REPORTERDAFRIQUE","description":"L&#039;Afrique au quotidien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reporterdafrique.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/reporterdafrique.info\/#\/schema\/person\/e6c969aa000793e687c5399b5ffbdc77","name":"reporterdafrique","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7882f7db2f0ee4f772f81ec0ee186273846b76223215f4b2a9c4f2b0017a1f64?s=96&d=mm&r=g","caption":"reporterdafrique"},"sameAs":["https:\/\/reporterdafrique.info"],"url":"https:\/\/reporterdafrique.info\/en\/author\/reporterdafrique\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/posts\/2725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/comments?post=2725"}],"version-history":[{"count":1,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/posts\/2725\/revisions"}],"predecessor-version":[{"id":2727,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/posts\/2725\/revisions\/2727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/media\/2726"}],"wp:attachment":[{"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/media?parent=2725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/categories?post=2725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporterdafrique.info\/en\/wp-json\/wp\/v2\/tags?post=2725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}